{"id":2806,"date":"2025-08-09T20:31:44","date_gmt":"2025-08-09T19:31:44","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/resurser\/"},"modified":"2025-10-15T20:17:12","modified_gmt":"2025-10-15T19:17:12","slug":"resurser","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/","title":{"rendered":"Resurser"},"content":{"rendered":"<div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">H\u00e5ll dig informerad om webbseminarier, utbildningsevenemang, n\u00e4tverk och forskningsm\u00f6jligheter fr\u00e5n olika organisationer som arbetar inom omr\u00e5det. Dessa resurser erbjuder v\u00e4rdefulla insikter f\u00f6r dem som \u00e4r intresserade av att l\u00e4ra sig mer om screening f\u00f6r lungcancer. Dessa sidor kommer att uppdateras regelbundet med nya m\u00f6jligheter n\u00e4r de blir tillg\u00e4ngliga.  <\/p>\n<\/div>","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2806","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resurser -%sitename%%%%.<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - en resurs f\u00f6r allm\u00e4nheten och yrkesverksamma inom lungcancerscreening.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resurser -%sitename%%%%.\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - en resurs f\u00f6r allm\u00e4nheten och yrkesverksamma inom lungcancerscreening.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T19:17:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/professionals\\\/resurser\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/professionals\\\/resurser\\\/\",\"name\":\"Resurser -%sitename%%%%.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/#website\"},\"datePublished\":\"2025-08-09T19:31:44+00:00\",\"dateModified\":\"2025-10-15T19:17:12+00:00\",\"description\":\"SOLACE Knowledge Hub - en resurs f\u00f6r allm\u00e4nheten och yrkesverksamma inom lungcancerscreening.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/professionals\\\/resurser\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/professionals\\\/resurser\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/professionals\\\/resurser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resurser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/sv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resurser -%sitename%%%%.","description":"SOLACE Knowledge Hub - en resurs f\u00f6r allm\u00e4nheten och yrkesverksamma inom lungcancerscreening.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/","og_locale":"sv_SE","og_type":"article","og_title":"Resurser -%sitename%%%%.","og_description":"SOLACE Knowledge Hub - en resurs f\u00f6r allm\u00e4nheten och yrkesverksamma inom lungcancerscreening.","og_url":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/","og_site_name":"Solace","article_modified_time":"2025-10-15T19:17:12+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/","url":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/","name":"Resurser -%sitename%%%%.","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/sv\/#website"},"datePublished":"2025-08-09T19:31:44+00:00","dateModified":"2025-10-15T19:17:12+00:00","description":"SOLACE Knowledge Hub - en resurs f\u00f6r allm\u00e4nheten och yrkesverksamma inom lungcancerscreening.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/sv\/professionals\/resurser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/sv\/"},{"@type":"ListItem","position":2,"name":"Resurser"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/sv\/#website","url":"https:\/\/hub.solacelung.eu\/sv\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/sv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/sv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/sv\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/sv\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/hub.solacelung.eu\/sv\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/sv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/sv\/wp-json\/wp\/v2\/professionals\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/sv\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/sv\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/sv\/wp-json\/wp\/v2\/professionals\/2806\/revisions"}],"predecessor-version":[{"id":2807,"href":"https:\/\/hub.solacelung.eu\/sv\/wp-json\/wp\/v2\/professionals\/2806\/revisions\/2807"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/sv\/wp-json\/wp\/v2\/media?parent=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}