{"id":3311,"date":"2025-08-09T20:19:56","date_gmt":"2025-08-09T19:19:56","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/"},"modified":"2026-06-10T22:28:23","modified_gmt":"2026-06-10T21:28:23","slug":"elegibilidade-e-avaliacao-dos-riscos","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/","title":{"rendered":"Elegibilidade e avalia\u00e7\u00e3o dos riscos"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Encontra recursos para definir a popula\u00e7\u00e3o-alvo dos programas de rastreio do cancro do pulm\u00e3o utilizando crit\u00e9rios de elegibilidade comprovados e modelos de risco validados centrados no historial de tabagismo, na idade e noutros factores de risco.<\/h3>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.uspreventiveservicestaskforce.org\/uspstf\/recommendation-topics\" target=\"_blank\" rel=\"noreferrer noopener\">A US Preventative Services Task Force recomenda<\/a> o rastreio anual com TC de baixa dose para adultos com idades compreendidas entre os 50 e os 80 anos que tenham um historial de 20 ma\u00e7os de tabaco por ano e que fumem atualmente ou tenham deixado de fumar nos \u00faltimos 15 anos.<\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.evidencio.com\/models\/show\/992\" target=\"_blank\" rel=\"noreferrer noopener\">O PLCOm2012 Risk Calculator <\/a>\u00e9 um modelo de risco multivari\u00e1vel validado para a elegibilidade do rastreio do cancro do pulm\u00e3o, incluindo a identifica\u00e7\u00e3o de indiv\u00edduos de alto risco para al\u00e9m dos crit\u00e9rios simples.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/doi.org\/10.1016\/j.lungcan.2020.07.007\" target=\"_blank\" rel=\"noreferrer noopener\">Toumaziz et al<\/a> resumem os modelos de previs\u00e3o do risco de cancro do pulm\u00e3o existentes e a sua aplica\u00e7\u00e3o no rastreio do cancro do pulm\u00e3o nesta revis\u00e3o sistem\u00e1tica.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/doi.org\/10.1016\/S2213-2600(23)00083-8\" target=\"_blank\" rel=\"noreferrer noopener\">Um artigo de coment\u00e1rio no Lancet<\/a> descreve a forma de otimizar os crit\u00e9rios de elegibilidade para o rastreio do cancro do pulm\u00e3o.  <\/li>\n<\/ul>\n<\/div>","protected":false},"featured_media":0,"parent":3249,"menu_order":4,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3311","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elegibilidade e avalia\u00e7\u00e3o dos riscos - Solace<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elegibilidade e avalia\u00e7\u00e3o dos riscos - Solace\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T21:28:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/elegibilidade-e-avaliacao-dos-riscos\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/elegibilidade-e-avaliacao-dos-riscos\\\/\",\"name\":\"Elegibilidade e avalia\u00e7\u00e3o dos riscos - Solace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-08-09T19:19:56+00:00\",\"dateModified\":\"2026-06-10T21:28:23+00:00\",\"description\":\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/elegibilidade-e-avaliacao-dos-riscos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/elegibilidade-e-avaliacao-dos-riscos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/elegibilidade-e-avaliacao-dos-riscos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conjunto de ferramentas de implementa\u00e7\u00e3o\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elegibilidade e avalia\u00e7\u00e3o dos riscos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elegibilidade e avalia\u00e7\u00e3o dos riscos - Solace","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/","og_locale":"pt_PT","og_type":"article","og_title":"Elegibilidade e avalia\u00e7\u00e3o dos riscos - Solace","og_description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","og_url":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/","og_site_name":"Solace","article_modified_time":"2026-06-10T21:28:23+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/","url":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/","name":"Elegibilidade e avalia\u00e7\u00e3o dos riscos - Solace","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website"},"datePublished":"2025-08-09T19:19:56+00:00","dateModified":"2026-06-10T21:28:23+00:00","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/elegibilidade-e-avaliacao-dos-riscos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Conjunto de ferramentas de implementa\u00e7\u00e3o","item":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/"},{"@type":"ListItem","position":3,"name":"Elegibilidade e avalia\u00e7\u00e3o dos riscos"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":2,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3311\/revisions"}],"predecessor-version":[{"id":4090,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3311\/revisions\/4090"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3249"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=3311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}