{"id":3066,"date":"2025-08-09T20:15:21","date_gmt":"2025-08-09T19:15:21","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/prova\/"},"modified":"2025-10-17T19:34:26","modified_gmt":"2025-10-17T18:34:26","slug":"prova","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/","title":{"rendered":"Prova"},"content":{"rendered":"<div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Ao longo das \u00faltimas d\u00e9cadas, t\u00eam-se acumulado provas que demonstram o valor para a sa\u00fade p\u00fablica do rastreio do cancro do pulm\u00e3o atrav\u00e9s de TCDA. Os principais ensaios efectuados nos EUA e na Europa revelaram resultados positivos: <\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.doi.org\/10.1056\/NEJMoa1102873\">Ensaio Nacional de Rastreio do Pulm\u00e3o (EUA) 2011<\/a>: O rastreio por LDCT reduziu as mortes por cancro do pulm\u00e3o em 20% em compara\u00e7\u00e3o com as radiografias do t\u00f3rax.  <\/li>\n\n\n\n<li><a href=\"http:\/\/www.doi.org\/10.1056\/NEJMoa1911793\">Ensaio NELSON (B\u00e9lgica e Pa\u00edses Baixos) 2020<\/a>: O rastreio por LDCT reduziu as mortes por cancro do pulm\u00e3o em 24% nos homens de alto risco ap\u00f3s 10 anos.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Ensaios europeus mais pequenos tamb\u00e9m confirmaram uma redu\u00e7\u00e3o da mortalidade por cancro do pulm\u00e3o devido \u00e0 despistagem:<\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/doi.org\/10.1093\/annonc\/mdz117\">Ensaio Multic\u00eantrico Italiano de Dete\u00e7\u00e3o Pulmonar (MILD) 2013<\/a>: uma redu\u00e7\u00e3o de 39% no risco de mortalidade por LC aos 10 anos.  <\/li>\n\n\n\n<li><a href=\"https:\/\/doi.org\/10.1002\/ijc.32486\">A Interven\u00e7\u00e3o Alem\u00e3 de Rastreio do Cancro do Pulm\u00e3o (LUSI)<\/a>: O rastreio por LDCT pode reduzir significativamente a mortalidade por cancro do pulm\u00e3o nas mulheres.  <\/li>\n\n\n\n<li><a href=\"https:\/\/doi.org\/10.1016\/S1470-2045(25)00082-8\">Ensaio SUMMIT<\/a>: a TCLA em larga escala \u00e9 eficaz e pode ser administrada de forma eficiente a uma popula\u00e7\u00e3o \u00e9tnica e socioecon\u00f3mica diversificada.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">No final de 2022, o Conselho Europeu actualizou as suas recomenda\u00e7\u00f5es de rastreio do cancro para incluir, pela primeira vez, o cancro do pulm\u00e3o. Com base nos resultados das provas cient\u00edficas, o Conselho incentivou todos os pa\u00edses europeus a explorarem a viabilidade e a efic\u00e1cia do rastreio do cancro do pulm\u00e3o utilizando a tomografia computorizada de baixa dose (LDCT). Esta iniciativa representa um importante passo em frente nos esfor\u00e7os de dete\u00e7\u00e3o precoce em todo o continente.  <\/p>\n<\/div>","protected":false},"featured_media":0,"parent":3521,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3066","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prova - Solace<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prova - Solace\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T18:34:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\\\/prova\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\\\/prova\\\/\",\"name\":\"Prova - Solace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-08-09T19:15:21+00:00\",\"dateModified\":\"2025-10-17T18:34:26+00:00\",\"description\":\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\\\/prova\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\\\/prova\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\\\/prova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porque \u00e9 que precisamos de fazer o rastreio do cancro?\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prova - Solace","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/","og_locale":"pt_PT","og_type":"article","og_title":"Prova - Solace","og_description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","og_url":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/","og_site_name":"Solace","article_modified_time":"2025-10-17T18:34:26+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/","url":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/","name":"Prova - Solace","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website"},"datePublished":"2025-08-09T19:15:21+00:00","dateModified":"2025-10-17T18:34:26+00:00","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/prova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Porque \u00e9 que precisamos de fazer o rastreio do cancro?","item":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/porque-e-que-precisamos-de-fazer-o-rastreio-do-cancro\/"},{"@type":"ListItem","position":3,"name":"Prova"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3066\/revisions"}],"predecessor-version":[{"id":3067,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3066\/revisions\/3067"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3521"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=3066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}