{"id":2195,"date":"2025-08-09T20:22:54","date_gmt":"2025-08-09T19:22:54","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/comunicacao-dos-resultados\/"},"modified":"2025-10-15T20:21:16","modified_gmt":"2025-10-15T19:21:16","slug":"comunicacao-dos-resultados","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/","title":{"rendered":"Comunica\u00e7\u00e3o dos resultados"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">\u00c9 necess\u00e1ria uma comunica\u00e7\u00e3o clara, compassiva e atempada para apresentar os resultados do rastreio. As evid\u00eancias e os recursos abaixo fornecem orienta\u00e7\u00f5es para as conversas de acompanhamento, a fim de garantir que os pacientes sejam informados e apoiados. <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><strong>As provas demonstram-no:  <\/strong><\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li>A tomada de decis\u00f5es partilhada <strong>\u00e9 essencial<\/strong>: a tomada de decis\u00f5es partilhada antes do rastreio do cancro do pulm\u00e3o \u00e9 uma parte crucial do programa para garantir que os doentes compreendem os benef\u00edcios, os riscos e os potenciais resultados. Isto pode promover o envolvimento dos doentes e alinhar as decis\u00f5es de rastreio com os valores pessoais, o que ajuda na fase de comunica\u00e7\u00e3o dos resultados.<a href=\"https:\/\/doi.org\/10.1001\/jama.2021.1817\">(JAMA<\/a>, 2024)  <br\/><br\/><\/li>\n\n\n\n<li><strong>O impacto psicol\u00f3gico varia<\/strong>: a rece\u00e7\u00e3o dos resultados do rastreio pode provocar ansiedade, ang\u00fastia ou al\u00edvio, dependendo dos resultados. Os resultados indeterminados ou falsos positivos podem causar preocupa\u00e7\u00e3o e incerteza prolongadas, real\u00e7ando a necessidade de uma comunica\u00e7\u00e3o sens\u00edvel e clara centrada na pessoa.<a href=\"https:\/\/doi.org\/10.21037\/tlcr-20-1179\">(Translational Lung Cancer Research<\/a>, 2021)  <br\/><br\/><\/li>\n\n\n\n<li><strong>A comunica\u00e7\u00e3o centrada no doente melhora os resultados<\/strong>: as revis\u00f5es sistem\u00e1ticas mostram que uma comunica\u00e7\u00e3o clara e adaptada e a explica\u00e7\u00e3o dos resultados podem ajudar os doentes a compreender os seus resultados e a gerir qualquer ang\u00fastia causada pelos resultados.<a href=\"https:\/\/doi.org\/10.1097\/jto.0000000000000210\">(Journal of Thoracic Oncology<\/a>, 2014)  <br\/><br\/><\/li>\n\n\n\n<li><strong>As narrativas e o apoio podem ajudar:<\/strong> fornecer explica\u00e7\u00f5es narrativas e apoio emocional juntamente com os resultados ajuda os doentes a processar a informa\u00e7\u00e3o e a gerir quaisquer efeitos psicol\u00f3gicos. O aconselhamento ou as chamadas de acompanhamento podem tamb\u00e9m abordar as preocupa\u00e7\u00f5es e orientar os passos seguintes<a href=\"https:\/\/doi.org\/10.21037\/shc-21-6\">(Official Journal of Shanghai Chest Hospital<\/a>, 2021)   <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>","protected":false},"featured_media":0,"parent":3249,"menu_order":8,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2195","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunica\u00e7\u00e3o dos resultados - Solace<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunica\u00e7\u00e3o dos resultados - Solace\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T19:21:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/comunicacao-dos-resultados\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/comunicacao-dos-resultados\\\/\",\"name\":\"Comunica\u00e7\u00e3o dos resultados - Solace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-08-09T19:22:54+00:00\",\"dateModified\":\"2025-10-15T19:21:16+00:00\",\"description\":\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/comunicacao-dos-resultados\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/comunicacao-dos-resultados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/comunicacao-dos-resultados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conjunto de ferramentas de implementa\u00e7\u00e3o\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/professionals\\\/conjunto-de-ferramentas-de-implementacao\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comunica\u00e7\u00e3o dos resultados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunica\u00e7\u00e3o dos resultados - Solace","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/","og_locale":"pt_PT","og_type":"article","og_title":"Comunica\u00e7\u00e3o dos resultados - Solace","og_description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","og_url":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/","og_site_name":"Solace","article_modified_time":"2025-10-15T19:21:16+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/","url":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/","name":"Comunica\u00e7\u00e3o dos resultados - Solace","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website"},"datePublished":"2025-08-09T19:22:54+00:00","dateModified":"2025-10-15T19:21:16+00:00","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/comunicacao-dos-resultados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Conjunto de ferramentas de implementa\u00e7\u00e3o","item":"https:\/\/hub.solacelung.eu\/pt-pt\/professionals\/conjunto-de-ferramentas-de-implementacao\/"},{"@type":"ListItem","position":3,"name":"Comunica\u00e7\u00e3o dos resultados"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/2195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/2195\/revisions"}],"predecessor-version":[{"id":2196,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/2195\/revisions\/2196"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/professionals\/3249"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=2195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}