{"id":2633,"date":"2025-08-09T19:57:35","date_gmt":"2025-08-09T18:57:35","guid":{"rendered":"https:\/\/hub.solacelung.eu\/patients\/diagnostico\/proximos-passos\/"},"modified":"2025-10-15T20:15:40","modified_gmt":"2025-10-15T19:15:40","slug":"proximos-passos","status":"publish","type":"patients","link":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/","title":{"rendered":"Pr\u00f3ximos passos"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">O cancro do pulm\u00e3o \u00e9 uma doen\u00e7a grave. Nos \u00faltimos anos, houve um grande aumento das op\u00e7\u00f5es de tratamento e est\u00e1 a ser feito muito trabalho para ajudar as pessoas a viver mais tempo e com melhor qualidade de vida.   <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Os m\u00e9dicos podem discutir o teu progn\u00f3stico &#8211; que descreve o caminho que acreditam que a doen\u00e7a ir\u00e1 tomar. A maior parte da informa\u00e7\u00e3o sobre o progn\u00f3stico \u00e9 dada em termos de uma &#8220;taxa de sobreviv\u00eancia a 5 anos&#8221;. Este termo \u00e9 frequentemente utilizado pelos profissionais de sa\u00fade e refere-se ao n\u00famero de pessoas que viveram durante 5 anos ou mais depois de terem sido diagnosticadas com diferentes tipos de cancro do pulm\u00e3o.  <\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">\u00c9 importante lembrar que cada pessoa \u00e9 diferente e que o teu tumor pode n\u00e3o responder ao tratamento da mesma forma que o tumor de outra pessoa. As estat\u00edsticas n\u00e3o reflectem necessariamente o que te vai acontecer. Deves encarar o teu progn\u00f3stico como um guia &#8211; e discuti-lo com o teu profissional de sa\u00fade.  <\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Existem v\u00e1rios tipos diferentes de cancro do pulm\u00e3o, que requerem uma s\u00e9rie de tratamentos diferentes. O teu plano de tratamento basear-se-\u00e1 no tipo e no est\u00e1dio do cancro do pulm\u00e3o que tens, no teu estado geral de sa\u00fade e nas tuas prefer\u00eancias pessoais. Os tratamentos podem centrar-se na cura do cancro do pulm\u00e3o (tratamentos curativos) ou em ajudar-te a viver mais tempo e com melhor qualidade de vida com o cancro do pulm\u00e3o (tratamentos paliativos).  <\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/europeanlung.org\/en\/information-hub\/lung-conditions\/lung-cancer\/#:~:text=with%20lung%20cancer-,Treatment,-%E2%80%9CIt%20is%20very\">Podes obter mais informa\u00e7\u00f5es sobre as op\u00e7\u00f5es de tratamento no s\u00edtio Web da European Lung Foundation.<\/a><\/strong><\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>","protected":false},"featured_media":0,"parent":2519,"menu_order":3,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2633","patients","type-patients","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00f3ximos passos - Solace<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00f3ximos passos - Solace\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T19:15:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/patients\\\/diagnostico\\\/proximos-passos\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/patients\\\/diagnostico\\\/proximos-passos\\\/\",\"name\":\"Pr\u00f3ximos passos - Solace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-08-09T18:57:35+00:00\",\"dateModified\":\"2025-10-15T19:15:40+00:00\",\"description\":\"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/patients\\\/diagnostico\\\/proximos-passos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/patients\\\/diagnostico\\\/proximos-passos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/patients\\\/diagnostico\\\/proximos-passos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diagn\u00f3stico\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/patients\\\/diagnostico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pr\u00f3ximos passos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00f3ximos passos - Solace","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/","og_locale":"pt_PT","og_type":"article","og_title":"Pr\u00f3ximos passos - Solace","og_description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","og_url":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/","og_site_name":"Solace","article_modified_time":"2025-10-15T19:15:40+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/","url":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/","name":"Pr\u00f3ximos passos - Solace","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website"},"datePublished":"2025-08-09T18:57:35+00:00","dateModified":"2025-10-15T19:15:40+00:00","description":"SOLACE Knowledge Hub - O recurso de rastreio do cancro do pulm\u00e3o para o p\u00fablico e os profissionais.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/proximos-passos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Diagn\u00f3stico","item":"https:\/\/hub.solacelung.eu\/pt-pt\/patients\/diagnostico\/"},{"@type":"ListItem","position":3,"name":"Pr\u00f3ximos passos"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#website","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/patients\/2633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/patients"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/types\/patients"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/patients\/2633\/revisions"}],"predecessor-version":[{"id":2634,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/patients\/2633\/revisions\/2634"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/patients\/2519"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=2633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}