{"id":3357,"date":"2025-08-09T20:21:01","date_gmt":"2025-08-09T19:21:01","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/"},"modified":"2026-06-10T22:24:35","modified_gmt":"2026-06-10T21:24:35","slug":"metodi-di-invito","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/","title":{"rendered":"Metodi di invito"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Scopri le strategie efficaci per invitare le persone idonee a partecipare allo screening.  <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Scopri le lettere personalizzate, i rinvii al medico di famiglia, la sensibilizzazione della comunit\u00e0, gli inviti combinati con quelli per altri screening oncologici e gli strumenti digitali per massimizzare la partecipazione:  <\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/doi.org\/10.1136\/thorax-2023-220001\" target=\"_blank\" rel=\"noreferrer noopener\">Goodley et al. <\/a>descrivono strategie di invito efficaci in un programma di screening del cancro al polmone basato sulla comunit\u00e0 in aree ad alta deprivazione socioeconomica.<br\/><br\/><\/li>\n\n\n\n<li>Il progetto SOLACE in Irlanda ha incluso due rappresentanti dei pazienti nel comitato direttivo per garantire che i metodi di coinvolgimento fossero modellati dai sostenitori della comunit\u00e0 a cui si rivolgeva.  <a href=\"https:\/\/youtu.be\/4qxz3O_B1Cw?si=lXe_vJPDy3LdP5HG\">Per saperne di pi\u00f9.<\/a><br\/><\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><strong>Risorse utili:<\/strong><\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Visita la <a href=\"https:\/\/hub.solacelung.eu\/it\/professionals\/politica-e-advocacy\/campagne-di-sensibilizzazione\/\">pagina di sensibilizzazione per<\/a> vedere esempi di comunicati stampa, video e poster utilizzati nei programmi di screening del cancro ai polmoni.  <\/p>\n<\/div>","protected":false},"featured_media":0,"parent":3253,"menu_order":5,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3357","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- %<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- %\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T21:24:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/metodi-di-invito\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/metodi-di-invito\\\/\",\"name\":\"- %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#website\"},\"datePublished\":\"2025-08-09T19:21:01+00:00\",\"dateModified\":\"2026-06-10T21:24:35+00:00\",\"description\":\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/metodi-di-invito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/metodi-di-invito\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/metodi-di-invito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toolkit di implementazione\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Metodi di invito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- %","description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/","og_locale":"it_IT","og_type":"article","og_title":"- %","og_description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","og_url":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/","og_site_name":"Solace","article_modified_time":"2026-06-10T21:24:35+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/","url":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/","name":"- %","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/it\/#website"},"datePublished":"2025-08-09T19:21:01+00:00","dateModified":"2026-06-10T21:24:35+00:00","description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/metodi-di-invito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Toolkit di implementazione","item":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/"},{"@type":"ListItem","position":3,"name":"Metodi di invito"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/it\/#website","url":"https:\/\/hub.solacelung.eu\/it\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/it\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hub.solacelung.eu\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":4,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3357\/revisions"}],"predecessor-version":[{"id":4000,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3357\/revisions\/4000"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3253"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/media?parent=3357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}