{"id":3087,"date":"2025-08-09T20:15:21","date_gmt":"2025-08-09T19:15:21","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/prove\/"},"modified":"2025-10-17T19:34:31","modified_gmt":"2025-10-17T18:34:31","slug":"prove","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/","title":{"rendered":"Prove"},"content":{"rendered":"<div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Negli ultimi decenni si stanno accumulando prove che dimostrano l&#8217;utilit\u00e0 per la salute pubblica dello screening del cancro al polmone mediante LDCT. Importanti studi negli Stati Uniti e in Europa hanno mostrato risultati positivi: <\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.doi.org\/10.1056\/NEJMoa1102873\">National Lung Screening Trial (USA) 2011<\/a>: Lo screening con LDCT ha ridotto i decessi per cancro ai polmoni del 20% rispetto alle radiografie del torace.  <\/li>\n\n\n\n<li><a href=\"http:\/\/www.doi.org\/10.1056\/NEJMoa1911793\">Studio NELSON (Belgio e Paesi Bassi) 2020<\/a>: Lo screening con LDCT ha ridotto del 24% i decessi per cancro al polmone negli uomini ad alto rischio dopo 10 anni.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Anche studi europei pi\u00f9 piccoli hanno confermato una riduzione della mortalit\u00e0 per cancro ai polmoni grazie allo screening:<\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/doi.org\/10.1093\/annonc\/mdz117\">Studio Multicentrico Italiano di Rilevazione Polmonare (MILD) 2013<\/a>: rischio ridotto del 39% di mortalit\u00e0 da LC a 10 anni.  <\/li>\n\n\n\n<li><a href=\"https:\/\/doi.org\/10.1002\/ijc.32486\">L&#8217;intervento tedesco di screening del cancro al polmone (LUSI)<\/a>: Lo screening con LDCT pu\u00f2 ridurre significativamente la mortalit\u00e0 per cancro al polmone nelle donne.  <\/li>\n\n\n\n<li><a href=\"https:\/\/doi.org\/10.1016\/S1470-2045(25)00082-8\">Lo studio SUMMIT<\/a>: la LDCT su larga scala \u00e8 efficace e pu\u00f2 essere somministrata in modo efficiente a una popolazione etnicamente e socioeconomicamente diversa.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Alla fine del 2022, il Consiglio Europeo ha aggiornato le sue raccomandazioni sullo screening dei tumori includendo per la prima volta il cancro ai polmoni. Sulla base dei risultati delle prove scientifiche, il Consiglio ha incoraggiato tutti i Paesi europei a esplorare la fattibilit\u00e0 e l&#8217;efficacia dello screening del tumore al polmone con la tomografia computerizzata a basso dosaggio (LDCT). Questo ha segnato un importante passo avanti negli sforzi di diagnosi precoce in tutto il continente.  <\/p>\n<\/div>","protected":false},"featured_media":0,"parent":3525,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3087","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- %<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- %\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T18:34:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\\\/prove\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\\\/prove\\\/\",\"name\":\"- %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#website\"},\"datePublished\":\"2025-08-09T19:15:21+00:00\",\"dateModified\":\"2025-10-17T18:34:31+00:00\",\"description\":\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\\\/prove\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\\\/prove\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\\\/prove\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch\u00e9 abbiamo bisogno di uno screening del cancro?\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prove\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- %","description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/","og_locale":"it_IT","og_type":"article","og_title":"- %","og_description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","og_url":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/","og_site_name":"Solace","article_modified_time":"2025-10-17T18:34:31+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/","url":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/","name":"- %","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/it\/#website"},"datePublished":"2025-08-09T19:15:21+00:00","dateModified":"2025-10-17T18:34:31+00:00","description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/prove\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Perch\u00e9 abbiamo bisogno di uno screening del cancro?","item":"https:\/\/hub.solacelung.eu\/it\/professionals\/perche-abbiamo-bisogno-di-uno-screening-del-cancro\/"},{"@type":"ListItem","position":3,"name":"Prove"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/it\/#website","url":"https:\/\/hub.solacelung.eu\/it\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/it\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hub.solacelung.eu\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3087\/revisions"}],"predecessor-version":[{"id":3088,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3087\/revisions\/3088"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3525"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/media?parent=3087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}