{"id":2227,"date":"2025-08-09T20:23:24","date_gmt":"2025-08-09T19:23:24","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/follow-up\/"},"modified":"2025-10-15T20:21:18","modified_gmt":"2025-10-15T19:21:18","slug":"follow-up","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/","title":{"rendered":"Follow-up"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">I programmi di screening del cancro al polmone utilizzano diversi protocolli per il follow-up dei pazienti, basati principalmente sui risultati della TAC iniziale a basso dosaggio.  <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Questi protocolli mirano a garantire una diagnosi e un trattamento tempestivi per chi ha un cancro ai polmoni sospetto o confermato, riducendo al minimo gli interventi non necessari per chi ha risultati benigni.<\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Presto verranno aggiunte altre prove e risorse sul follow-up dei pazienti.  <\/p>\n<\/div>","protected":false},"featured_media":0,"parent":3253,"menu_order":9,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2227","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- %<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- %\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T19:21:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/follow-up\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/follow-up\\\/\",\"name\":\"- %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#website\"},\"datePublished\":\"2025-08-09T19:23:24+00:00\",\"dateModified\":\"2025-10-15T19:21:18+00:00\",\"description\":\"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/follow-up\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/follow-up\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/follow-up\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toolkit di implementazione\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/professionals\\\/toolkit-di-implementazione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Follow-up\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- %","description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/","og_locale":"it_IT","og_type":"article","og_title":"- %","og_description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","og_url":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/","og_site_name":"Solace","article_modified_time":"2025-10-15T19:21:18+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/","url":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/","name":"- %","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/it\/#website"},"datePublished":"2025-08-09T19:23:24+00:00","dateModified":"2025-10-15T19:21:18+00:00","description":"SOLACE Knowledge Hub - La risorsa per lo screening del cancro al polmone per il pubblico e i professionisti.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/follow-up\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Toolkit di implementazione","item":"https:\/\/hub.solacelung.eu\/it\/professionals\/toolkit-di-implementazione\/"},{"@type":"ListItem","position":3,"name":"Follow-up"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/it\/#website","url":"https:\/\/hub.solacelung.eu\/it\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/it\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hub.solacelung.eu\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/2227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/2227\/revisions"}],"predecessor-version":[{"id":2228,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/2227\/revisions\/2228"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/professionals\/3253"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/it\/wp-json\/wp\/v2\/media?parent=2227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}