{"id":3385,"date":"2025-08-09T20:23:59","date_gmt":"2025-08-09T19:23:59","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/"},"modified":"2025-10-16T00:13:59","modified_gmt":"2025-10-15T23:13:59","slug":"gestion-des-donnees","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/","title":{"rendered":"Gestion des donn\u00e9es"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Garantir des syst\u00e8mes solides pour la collecte, le suivi et la communication des donn\u00e9es. Cette section couvre la conception des registres et le respect des r\u00e9glementations en mati\u00e8re de protection des donn\u00e9es.   <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Les faits le prouvent :  <\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><strong>Une collecte de donn\u00e9es compl\u00e8te est n\u00e9cessaire : les<\/strong> programmes de d\u00e9pistage n\u00e9cessitent divers types de donn\u00e9es, notamment les donn\u00e9es d\u00e9mographiques des patients, les ant\u00e9c\u00e9dents de tabagisme, les r\u00e9sultats de l&rsquo;imagerie et les r\u00e9sultats du suivi. Ces donn\u00e9es permettent de d\u00e9terminer l&rsquo;\u00e9ligibilit\u00e9, le suivi et l&rsquo;\u00e9valuation.<a href=\"https:\/\/www.lungcancerpolicynetwork.com\/app\/uploads\/Types-of-data-and-requirements-for-setting-up-screening-programme.pdf\">(R\u00e9seau pour la politique en mati\u00e8re de cancer du poumon<\/a>).<br\/><br\/><\/li>\n\n\n\n<li>L&rsquo;int\u00e9gration <strong>avec les dossiers m\u00e9dicaux \u00e9lectroniques (DME) est utile : l<\/strong> &lsquo;int\u00e9gration des donn\u00e9es de d\u00e9pistage dans les DME facilite le suivi continu des informations relatives aux patients et am\u00e9liore la coordination des soins. Toutefois, il est difficile de documenter avec pr\u00e9cision les ant\u00e9c\u00e9dents de tabagisme et d&rsquo;assurer l&rsquo;interop\u00e9rabilit\u00e9 entre les syst\u00e8mes. (<em>\n  <a href=\"https:\/\/doi.org\/10.1016\/j.chest.2019.12.004\">CHEST<\/a>\n<\/em>, 2020).  <br\/><br\/><\/li>\n\n\n\n<li><strong>Les entrep\u00f4ts de donn\u00e9es peuvent \u00eatre utilis\u00e9s pour le suivi des performances : les<\/strong> entrep\u00f4ts de donn\u00e9es centralis\u00e9s permettent la collecte et l&rsquo;analyse syst\u00e9matiques des donn\u00e9es de d\u00e9pistage dans toutes les r\u00e9gions. Cette approche permet de suivre les performances du programme et d&rsquo;identifier les disparit\u00e9s, notamment celles li\u00e9es au statut socio-\u00e9conomique. (<em>\n  <a href=\"https:\/\/doi.org\/10.1093\/eurpub\/ckaf119\">Revue europ\u00e9enne de sant\u00e9 publique<\/a>\n<\/em>, 2025).<br\/><br\/><\/li>\n\n\n\n<li><strong>La normalisation des indicateurs est n\u00e9cessaire : <\/strong>l&rsquo;\u00e9laboration et l&rsquo;adoption d&rsquo;un ensemble commun d&rsquo;indicateurs permettent d&rsquo;\u00e9valuer et de comparer de mani\u00e8re coh\u00e9rente les performances des diff\u00e9rents programmes de d\u00e9pistage, ce qui facilite les efforts d&rsquo;am\u00e9lioration de la qualit\u00e9. (<em>\n  <a href=\"https:\/\/doi.org\/10.1093\/eurpub\/ckaf119\">Revue europ\u00e9enne de sant\u00e9 publique<\/a>\n<\/em>, 2025).<br\/><br\/><\/li>\n\n\n\n<li><strong>Gouvernance et cadres d&rsquo;\u00e9valuation :<\/strong> la mise en place de structures de gouvernance et de cadres d&rsquo;\u00e9valuation solides garantit la responsabilit\u00e9 et l&rsquo;am\u00e9lioration continue des programmes de d\u00e9pistage. Il s&rsquo;agit notamment de d\u00e9finir les r\u00f4les, les responsabilit\u00e9s et les processus de gestion des donn\u00e9es et d&rsquo;\u00e9valuation des programmes.<a href=\"https:\/\/www.lungcancerpolicynetwork.com\/app\/uploads\/Types-of-data-and-requirements-for-setting-up-screening-programme.pdf\">(R\u00e9seau d&rsquo;action contre le cancer du poumon<\/a>).  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><strong>Ressources utiles :  <\/strong><\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">R\u00e9seau d&rsquo;action contre le cancer du poumon : <a href=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Types-of-data-and-requirements-for-setting-up-screening-programme-1.pdf\">Types de donn\u00e9es et exigences (PDF).<\/a><\/p>\n<\/div>","protected":false},"featured_media":0,"parent":3264,"menu_order":10,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3385","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestion des donn\u00e9es - Solace.<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestion des donn\u00e9es - Solace.\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T23:13:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/boite-a-outils-de-mise-en-oeuvre\\\/gestion-des-donnees\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/boite-a-outils-de-mise-en-oeuvre\\\/gestion-des-donnees\\\/\",\"name\":\"Gestion des donn\u00e9es - Solace.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#website\"},\"datePublished\":\"2025-08-09T19:23:59+00:00\",\"dateModified\":\"2025-10-15T23:13:59+00:00\",\"description\":\"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/boite-a-outils-de-mise-en-oeuvre\\\/gestion-des-donnees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/boite-a-outils-de-mise-en-oeuvre\\\/gestion-des-donnees\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/boite-a-outils-de-mise-en-oeuvre\\\/gestion-des-donnees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bo\u00eete \u00e0 outils de mise en \u0153uvre\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/boite-a-outils-de-mise-en-oeuvre\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gestion des donn\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestion des donn\u00e9es - Solace.","description":"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/","og_locale":"fr_FR","og_type":"article","og_title":"Gestion des donn\u00e9es - Solace.","og_description":"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.","og_url":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/","og_site_name":"Solace","article_modified_time":"2025-10-15T23:13:59+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/","url":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/","name":"Gestion des donn\u00e9es - Solace.","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/fr\/#website"},"datePublished":"2025-08-09T19:23:59+00:00","dateModified":"2025-10-15T23:13:59+00:00","description":"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/gestion-des-donnees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Bo\u00eete \u00e0 outils de mise en \u0153uvre","item":"https:\/\/hub.solacelung.eu\/fr\/professionals\/boite-a-outils-de-mise-en-oeuvre\/"},{"@type":"ListItem","position":3,"name":"Gestion des donn\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/fr\/#website","url":"https:\/\/hub.solacelung.eu\/fr\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/fr\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hub.solacelung.eu\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/3385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":1,"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/3385\/revisions"}],"predecessor-version":[{"id":3386,"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/3385\/revisions\/3386"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/3264"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/media?parent=3385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}