{"id":2277,"date":"2025-08-09T20:28:08","date_gmt":"2025-08-09T19:28:08","guid":{"rendered":"https:\/\/hub.solacelung.eu\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/"},"modified":"2026-06-10T22:29:22","modified_gmt":"2026-06-10T21:29:22","slug":"campagnes-de-sensibilisation","status":"publish","type":"professionals","link":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/","title":{"rendered":"Campagnes de sensibilisation"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Une communication efficace est essentielle pour sensibiliser et encourager la participation au d\u00e9pistage du cancer du poumon.  <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Trouvez des exemples de campagnes destin\u00e9es aux patients et de strat\u00e9gies de presse et de m\u00e9dias con\u00e7ues pour aider les professionnels de la sant\u00e9 et les d\u00e9fenseurs des droits de l&rsquo;homme \u00e0 impliquer les patients, les d\u00e9cideurs politiques et le public.<\/p>\n<\/div><div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Communiqu\u00e9s de presse  <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkos.cz\/onkologicka-prevence\/screening\/program-screeningu-karcinomu-plic\/80-nebo-10-sance-na-preziti-rozdil-mezi-stadii-rakoviny-plic-je-dramaticky\/\">Des communiqu\u00e9s de presse ont \u00e9t\u00e9 diffus\u00e9s par le programme de d\u00e9pistage du cancer du poumon en Tch\u00e9coslovaquie <\/a>avant le lancement du programme afin de sensibiliser le public et de susciter sa participation.  <\/p>\n<\/div><div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Vid\u00e9os de recrutement  <\/h3>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li>Trois vid\u00e9os d&rsquo;animation ont \u00e9t\u00e9 produites dans le cadre du projet SOLACE, couvrant une s\u00e9rie de sujets :  <div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/youtu.be\/2Z6p6tev_6Y\">Qui peut b\u00e9n\u00e9ficier du d\u00e9pistage du cancer du poumon ?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/youtu.be\/e9ngk-oEU68\">Que se passe-t-il pendant le d\u00e9pistage du cancer du poumon ?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/youtu.be\/L_v3FuNY4Oc\">Aborder les id\u00e9es re\u00e7ues sur le d\u00e9pistage du cancer du poumon<\/a><br\/>Si vous souhaitez que ces vid\u00e9os soient traduites dans votre langue, <a href=\"https:\/\/europeanlung.org\/solace\/contact\/\">veuillez nous contacter.<\/a> <br\/> <br\/><\/li>\n<\/ul>\n<\/div><\/li>\n\n\n\n<li>L&rsquo;Irish Lung Health check a d\u00e9velopp\u00e9 une s\u00e9rie de vid\u00e9os pour aider \u00e0 promouvoir le programme et sensibiliser au d\u00e9pistage du cancer du poumon.  <a href=\"https:\/\/youtube.com\/@lunghealthcheck?si=p3GpiQNWtbiCLXtt\">Regardez la s\u00e9rie de vid\u00e9os.<\/a><br\/><\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Affiches de recrutement  <\/h3>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li>Les projets pilotes de SOLACE ont produit diff\u00e9rentes affiches de recrutement adapt\u00e9es \u00e0 des publics sp\u00e9cifiques. <a href=\"https:\/\/europeanlung.org\/solace\/project-resources\/#:~:text=overview%20flyer%20%2D%20English-,Lung%20cancer%20screening%20recruitment%20poster%20for%20women,-Download%20a%20lung\">Voir tous les documents<\/a>.  <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><div class=\"site-padding\">\n<ul class=\"wp-block-list\">\n<li>Les associations de patients du Royaume-Uni ont collabor\u00e9 avec le Service national de sant\u00e9 (NHS) pour \u00e9laborer des campagnes de promotion du d\u00e9pistage du cancer du poumon. Ces campagnes ont n\u00e9cessit\u00e9 des recherches approfondies sur le langage le plus appropri\u00e9 pour cibler la population g\u00e9n\u00e9rale et l&rsquo;encourager \u00e0 participer \u00e0 un programme de d\u00e9pistage. Les campagnes se sont concentr\u00e9es sur l&rsquo;id\u00e9e de \u00ab\u00a0r\u00e9viser\u00a0\u00bb vos poumons (un MOT), comme vous le feriez pour une voiture. Elles s&rsquo;adressaient sp\u00e9cifiquement \u00e0 un public masculin d&rsquo;une soixantaine d&rsquo;ann\u00e9es susceptible de s&rsquo;identifier \u00e0 cette terminologie.   <\/li>\n<\/ul>\n<\/div><div class=\"site-padding\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"429\" height=\"611\" src=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png\" alt=\"\" class=\"wp-image-807\" style=\"aspect-ratio:0.7021300659754948;width:218px;height:auto\" srcset=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png 429w, https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign-344x490.png 344w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><\/figure>\n<\/div>","protected":false},"featured_media":0,"parent":2241,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2277","professionals","type-professionals","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campagnes de sensibilisation - Solace.<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagnes de sensibilisation - Solace.\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T21:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png\" \/>\n\t<meta property=\"og:image:width\" content=\"429\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/\",\"name\":\"Campagnes de sensibilisation - Solace.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.solacelung.eu\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nottingham-campaign.png\",\"datePublished\":\"2025-08-09T19:28:08+00:00\",\"dateModified\":\"2026-06-10T21:29:22+00:00\",\"description\":\"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nottingham-campaign.png\",\"contentUrl\":\"https:\\\/\\\/hub.solacelung.eu\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nottingham-campaign.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/campagnes-de-sensibilisation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique et plaidoyer\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/professionals\\\/politique-et-plaidoyer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campagnes de sensibilisation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagnes de sensibilisation - Solace.","description":"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/","og_locale":"fr_FR","og_type":"article","og_title":"Campagnes de sensibilisation - Solace.","og_description":"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.","og_url":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/","og_site_name":"Solace","article_modified_time":"2026-06-10T21:29:22+00:00","og_image":[{"width":429,"height":611,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/","url":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/","name":"Campagnes de sensibilisation - Solace.","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/#primaryimage"},"image":{"@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png","datePublished":"2025-08-09T19:28:08+00:00","dateModified":"2026-06-10T21:29:22+00:00","description":"SOLACE Knowledge Hub - La ressource en mati\u00e8re de d\u00e9pistage du cancer du poumon pour le public et les professionnels.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/#primaryimage","url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png","contentUrl":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/Nottingham-campaign.png"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/campagnes-de-sensibilisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique et plaidoyer","item":"https:\/\/hub.solacelung.eu\/fr\/professionals\/politique-et-plaidoyer\/"},{"@type":"ListItem","position":3,"name":"Campagnes de sensibilisation"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/fr\/#website","url":"https:\/\/hub.solacelung.eu\/fr\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/fr\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hub.solacelung.eu\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/2277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/types\/professionals"}],"version-history":[{"count":2,"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/2277\/revisions"}],"predecessor-version":[{"id":4110,"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/2277\/revisions\/4110"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/professionals\/2241"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/fr\/wp-json\/wp\/v2\/media?parent=2277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}