{"id":2985,"date":"2025-08-09T19:56:07","date_gmt":"2025-08-09T18:56:07","guid":{"rendered":"https:\/\/hub.solacelung.eu\/patients\/diagnostico\/resultados\/"},"modified":"2025-10-15T20:18:54","modified_gmt":"2025-10-15T19:18:54","slug":"resultados","status":"publish","type":"patients","link":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/","title":{"rendered":"Resultados"},"content":{"rendered":"<div class=\"site-padding\">\n<h3 class=\"wp-block-heading\">Si tu m\u00e9dico cree que tienes c\u00e1ncer de pulm\u00f3n, te pedir\u00e1 algunas pruebas que pueden mostrar hasta d\u00f3nde se ha extendido el c\u00e1ncer, conocidas como pruebas de estadificaci\u00f3n.  <\/h3>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Las pruebas de estadificaci\u00f3n tambi\u00e9n proporcionan informaci\u00f3n \u00fatil sobre el mejor lugar del que recoger una muestra de tejido. El estadio de tu c\u00e1ncer de pulm\u00f3n es uno de los factores que ayudar\u00e1n a tus profesionales sanitarios a decidir el mejor tipo de tratamiento que pueden ofrecerte. <a href=\"https:\/\/hub.solacelung.eu\/uk\/patients\/%d0%b4%d1%96%d0%b0%d0%b3%d0%bd%d0%be%d0%b7\/%d1%82%d0%b5%d1%81%d1%82%d0%b8\/\">Visita la p\u00e1gina de pruebas<\/a> para saber m\u00e1s. <\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Cuando el c\u00e1ncer de pulm\u00f3n se diagnostica despu\u00e9s de que hayan aparecido los s\u00edntomas, suele encontrarse en una fase avanzada. Cuando el c\u00e1ncer de pulm\u00f3n se detecta en el marco de un programa de cribado de c\u00e1ncer de pulm\u00f3n, suele detectarse en una fase temprana, cuando es m\u00e1s probable que los tratamientos para curarlo tengan m\u00e1s \u00e9xito. <\/p>\n<\/div><div class=\"site-padding\">\n<p class=\"wp-block-paragraph\">Que te digan que tienes c\u00e1ncer de pulm\u00f3n puede ser devastador. Muchas personas con c\u00e1ncer de pulm\u00f3n descubren que poder hablar con alguien ajeno a su familia, como un consejero o un psic\u00f3logo, a menudo puede ayudarles. Si crees que esto puede ser \u00fatil para ti, habla con tu m\u00e9dico sobre los servicios disponibles en tu zona.  <\/p>\n<\/div>","protected":false},"featured_media":0,"parent":2971,"menu_order":2,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2985","patients","type-patients","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resultados - %<\/title>\n<meta name=\"description\" content=\"SOLACE Knowledge Hub - El recurso de cribado del c\u00e1ncer de pulm\u00f3n para el p\u00fablico y los profesionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados - %\" \/>\n<meta property=\"og:description\" content=\"SOLACE Knowledge Hub - El recurso de cribado del c\u00e1ncer de pulm\u00f3n para el p\u00fablico y los profesionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/\" \/>\n<meta property=\"og:site_name\" content=\"Solace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T19:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/patients\\\/diagnostico\\\/resultados\\\/\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/patients\\\/diagnostico\\\/resultados\\\/\",\"name\":\"Resultados - %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/#website\"},\"datePublished\":\"2025-08-09T18:56:07+00:00\",\"dateModified\":\"2025-10-15T19:18:54+00:00\",\"description\":\"SOLACE Knowledge Hub - El recurso de cribado del c\u00e1ncer de pulm\u00f3n para el p\u00fablico y los profesionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/patients\\\/diagnostico\\\/resultados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/patients\\\/diagnostico\\\/resultados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/patients\\\/diagnostico\\\/resultados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diagn\u00f3stico\",\"item\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/patients\\\/diagnostico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Resultados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/\",\"name\":\"Solace\",\"description\":\"Solace\",\"publisher\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/#organization\",\"name\":\"Solace\",\"url\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Solace\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.solacelung.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/105992869\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados - %","description":"SOLACE Knowledge Hub - El recurso de cribado del c\u00e1ncer de pulm\u00f3n para el p\u00fablico y los profesionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/","og_locale":"es_ES","og_type":"article","og_title":"Resultados - %","og_description":"SOLACE Knowledge Hub - El recurso de cribado del c\u00e1ncer de pulm\u00f3n para el p\u00fablico y los profesionales.","og_url":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/","og_site_name":"Solace","article_modified_time":"2025-10-15T19:18:54+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/hub.solacelung.eu\/wp-content\/uploads\/2025\/08\/shutterstock_1998552674.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/","url":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/","name":"Resultados - %","isPartOf":{"@id":"https:\/\/hub.solacelung.eu\/es\/#website"},"datePublished":"2025-08-09T18:56:07+00:00","dateModified":"2025-10-15T19:18:54+00:00","description":"SOLACE Knowledge Hub - El recurso de cribado del c\u00e1ncer de pulm\u00f3n para el p\u00fablico y los profesionales.","breadcrumb":{"@id":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/resultados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.solacelung.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Diagn\u00f3stico","item":"https:\/\/hub.solacelung.eu\/es\/patients\/diagnostico\/"},{"@type":"ListItem","position":3,"name":"Resultados"}]},{"@type":"WebSite","@id":"https:\/\/hub.solacelung.eu\/es\/#website","url":"https:\/\/hub.solacelung.eu\/es\/","name":"Solace","description":"Solace","publisher":{"@id":"https:\/\/hub.solacelung.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.solacelung.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hub.solacelung.eu\/es\/#organization","name":"Solace","url":"https:\/\/hub.solacelung.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hub.solacelung.eu\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Solace"},"image":{"@id":"https:\/\/hub.solacelung.eu\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/105992869\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/patients\/2985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/patients"}],"about":[{"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/types\/patients"}],"version-history":[{"count":2,"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/patients\/2985\/revisions"}],"predecessor-version":[{"id":3000,"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/patients\/2985\/revisions\/3000"}],"up":[{"embeddable":true,"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/patients\/2971"}],"wp:attachment":[{"href":"https:\/\/hub.solacelung.eu\/es\/wp-json\/wp\/v2\/media?parent=2985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}